{"id":3270,"date":"2017-01-09T06:38:54","date_gmt":"2017-01-09T06:38:54","guid":{"rendered":"https:\/\/research.utm.my\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg"},"modified":"2017-01-09T06:38:54","modified_gmt":"2017-01-09T06:38:54","slug":"whatsapp-image-2016-12-21-at-5-35-55-pm1","status":"inherit","type":"attachment","link":"https:\/\/research.utm.my\/che\/whatsapp-image-2016-12-21-at-5-35-55-pm1\/","title":{"rendered":"WhatsApp Image 2016-12-21 at 5.35.55 PM(1)"},"author":11315,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ngg_post_thumbnail":0},"class_list":["post-3270","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-300x169.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-300x169.jpeg 300w, https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-1024x576.jpeg 1024w, https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":720,"file":"2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg","sizes":{"thumbnail":{"file":"WhatsApp-Image-2016-12-21-at-5.35.55-PM1-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-150x150.jpeg"},"medium":{"file":"WhatsApp-Image-2016-12-21-at-5.35.55-PM1-300x169.jpeg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-300x169.jpeg"},"large":{"file":"WhatsApp-Image-2016-12-21-at-5.35.55-PM1-1024x576.jpeg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-1024x576.jpeg"},"home-bottom":{"file":"WhatsApp-Image-2016-12-21-at-5.35.55-PM1-150x130.jpeg","width":150,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-150x130.jpeg"},"home-middle":{"file":"WhatsApp-Image-2016-12-21-at-5.35.55-PM1-287x120.jpeg","width":287,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1-287x120.jpeg"},"full":{"file":"WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg","width":1280,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/research.utm.my\/che\/wp-content\/uploads\/sites\/45\/2017\/01\/WhatsApp-Image-2016-12-21-at-5.35.55-PM1.jpeg","_links":{"self":[{"href":"https:\/\/research.utm.my\/che\/wp-json\/wp\/v2\/media\/3270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.utm.my\/che\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/research.utm.my\/che\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/research.utm.my\/che\/wp-json\/wp\/v2\/users\/11315"}],"replies":[{"embeddable":true,"href":"https:\/\/research.utm.my\/che\/wp-json\/wp\/v2\/comments?post=3270"}]}}